{"id":600,"date":"2022-04-21T20:15:00","date_gmt":"2022-04-21T20:15:00","guid":{"rendered":"https:\/\/english-content.com\/?p=600"},"modified":"2022-07-04T11:08:06","modified_gmt":"2022-07-04T11:08:06","slug":"wie-man-einen-texter-brieft","status":"publish","type":"post","link":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft","title":{"rendered":"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1 fusion-builder-column-0 fusion-one-full fusion-column-first fusion-column-last 1_1\"  style='margin-top:0px;margin-bottom:0px;'><div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\"><div class=\"fusion-text\"><h2>Bevor Sie einen Content-Writer oder einen Content-Marketing-Strategen beauftragen, sollten Sie sich etwas Zeit nehmen, um ein detailliertes Briefing zu entwerfen. Das wird Ihnen und dem Kreativen aus mehreren Gr\u00fcnden zugutekommen.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"lazyload aligncenter size-full wp-image-396\" src=\"https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy.jpg\" data-orig-src=\"https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy.jpg\" alt=\"\" width=\"1200\" height=\"629\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27629%27%20viewBox%3D%270%200%201200%20629%27%3E%3Crect%20width%3D%271200%27%20height%3D%273629%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy-200x105.jpg 200w, https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy-300x157.jpg 300w, https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy-400x210.jpg 400w, https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy-600x315.jpg 600w, https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy-768x403.jpg 768w, https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy-800x419.jpg 800w, https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy-1024x537.jpg 1024w, https:\/\/english-content.com\/wp-content\/uploads\/2021\/02\/content-marketing-writing-and-strategy.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Die Entwicklung eines Briefings f\u00fcr einen Copywriter, Content Creator oder Strategen bringt Sie dazu, \u00fcber Ihre Ziele nachzudenken und erleichtert einen effizienten Projektverlauf:<\/p>\n<ul>\n<li>Erstens hilft ein gutes Briefing Ihnen und dem Kreativen, Missverst\u00e4ndnisse \u00fcber den Umfang zu vermeiden. So kann das Projekt reibungslos geplant und umgesetzt werden.<\/li>\n<li>Zweitens kann der Kreative Ihnen durch ein gut durchdachtes Briefing eine genaue Kalkulation der entstehenden Kosten geben.<\/li>\n<li>Drittens: Durch die Erstellung eines detaillierten Briefings konzentrieren Sie sich auf das, was Sie wirklich f\u00fcr das Projekt brauchen. Diese \u00dcbung zwingt Sie dazu, Ihre Gesch\u00e4ftsziele zu \u00fcberdenken und herauszufinden, was genau notwendig ist, um diese Ziele zu erreichen. So k\u00f6nnen Sie Ihre Content-Anforderungen anschlie\u00dfend genau formulieren bzw. planen.<\/li>\n<li>Wenn Sie sich die Zeit nehmen, ein detailliertes Briefing zu verfassen, werden Sie au\u00dferdem ein besseres Verst\u00e4ndnis daf\u00fcr entwickeln, was Sie von dem Kreativen ben\u00f6tigen. Brauchen Sie neben den Inhalten auch eine Strategie? Soll der Kreative eine Keyword-Recherche durchf\u00fchren? Brauchen Sie einen regelm\u00e4\u00dfigen Nachschub an Blogs pro Monat?<\/li>\n<\/ul>\n<p>Hier einige Fragen, die Sie sich stellen sollten, bevor Sie Ihr Briefing schreiben:<\/p>\n<h2>Welche Dienstleistung ben\u00f6tige ich? Englischsprachigen Content- oder eine Content-Strategie?<\/h2>\n<p>Heutzutage ist Marketing ganz wesentlich auch Content-Marketing. Aber allein das Erstellen von Inhalten, wie Blogs, Videos und anderen Content-Arten f\u00fchrt nicht automatisch zum Marketingerfolg. Im Rahmen einer Strategie-Entwicklung identifizieren Sie Ihre Kunden und verstehen, wo diese sich online aufhalten beziehungsweise welche Themen sie in den Phasen der Customer Journey interessieren. Wenn Sie andererseits lediglich Content ben\u00f6tigen, der zu einer bestehenden Strategie passen soll, ist zu \u00fcberlegen, welche Art von Inhalten den Erfolg Ihrer Strategie sicherstellt?<\/p>\n<h2>Warum muss dieser Artikel geschrieben werden? Was ist sein Zweck?<\/h2>\n<p>Soll der ben\u00f6tigte Content Autorit\u00e4t aufbauen und Expertise und Thought-Leadership demonstrieren? Oder handelt es sich um eine Informationsbrosch\u00fcre f\u00fcr Kollegen, die als Teil eines internen Kommunikationsprogramms ver\u00f6ffentlicht werden soll? Oder soll ein Text Kunden \u00fcber ein Produkt, eine L\u00f6sung oder eine Veranstaltung informieren? Denken Sie \u00fcber das Ziel Ihrer Inhalte nach.<\/p>\n<h2>F\u00fcr wen wird der Content geschrieben?<\/h2>\n<p>Definieren Sie Ihr Zielpublikum. An wen soll der Content gerichtet sein? An Gesch\u00e4ftskunden, Verbraucher, eine bestimmte Altersgruppe oder ein Geschlecht? Gibt es Personae, die von diesem Content \u00fcberzeugt werden sollen? Haben Sie dar\u00fcber nachgedacht, in welcher Phase der Customer Journey dieser Content erscheinen soll? Selbstverst\u00e4ndlich unterst\u00fctzen wir Sie auch bereits bei diesen Gedanken.<\/p>\n<h2>Welche Art von Sprache soll verwendet werden? Gibt es eine Brand Voice, die zu ber\u00fccksichtigen ist?<\/h2>\n<p>Soll der Inhalt in hochgradig beschreibender, redaktioneller Sprache oder in Klartext geschrieben werden? Soll der Stil formell oder informell sein? Gibt es eine eigene Brand Voice, die in der Sprache zum Ausdruck kommen sollte? Gro\u00dfe Marken haben einen sehr klaren Kommunikationsstil. <a href=\"https:\/\/about.nike.com\/\" target=\"_blank\" rel=\"noopener\">Texte von Nike zum Beispiel sind inspirierend, stark und positiv<\/a> und unterstreichen das sportliche Herz der Marke. <a href=\"https:\/\/www.patagonia.com\/activism\/\" target=\"_blank\" rel=\"noopener\">Patagonia, mit dem Schutz der Umwelt als Grundwert, ist eher emotional, f\u00fcrsorglich, bescheiden und kooperativ<\/a>. Stellen Sie sicher, dass der Texter Zugang zu den Styleguides der Marke hat, oder geben Sie ein paar Zeilen an, die die Art der ben\u00f6tigten Sprache verdeutlichen.<\/p>\n<h2>Gibt es ein bestimmtes Problem und eine L\u00f6sung, die in dem Beitrag pr\u00e4sentiert werden sollen?<\/h2>\n<p>Wie hilft Ihr Unternehmen seinen Kunden? Welche Art von Problem k\u00f6nnte ein potenzieller Kunde haben, das ihn dazu veranlasst, nach Ihrem Produkt oder Ihrer L\u00f6sung zu suchen? Ist dies ein Ansatz, der im Text aufgegriffen werden sollte?<\/p>\n<h2>Auf welchen Kan\u00e4len wird der Content erscheinen?<\/h2>\n<p>Wird der Content auf der Website als Blog ver\u00f6ffentlicht? Soll er im Intranet pr\u00e4sentiert werden? Kann er an anderer Stelle in einem anderen Format wiederverwendet werden? Soll der Texter Social-Media-Posts erstellen, um den Website-Content zu unterst\u00fctzen und sicherzustellen, dass er effektiv beworben wird?<\/p>\n<h2>Welche Art von Reaktion soll der Content-Beitrag hervorrufen?<\/h2>\n<p>Soll der Beitrag Aufmerksamkeit f\u00fcr Ihr Unternehmen schaffen, Kunden auf die Website bringen oder sie dazu bringen, sich f\u00fcr ein Webinar anzumelden?<\/p>\n<h2>Ein paar Gedanken zum Schluss:<\/h2>\n<ul>\n<li>Seien Sie sich im Klaren dar\u00fcber, welche Leistungen Sie von dem Kreativen ben\u00f6tigen.<\/li>\n<li>Entscheiden Sie sich f\u00fcr die Wortzahl oder die L\u00e4nge des Textes.<\/li>\n<li>Beziehen Sie <a href=\"https:\/\/english-content.com\/de\/einfache-seo-tipps-fuer-blogs-in-2021\" target=\"_blank\" rel=\"noopener\">Keywords ein oder machen Sie die Keywordrecherche zum Bestandteil des Briefings<\/a>.<\/li>\n<li>\u00dcberlegen Sie, wer die Recherche durchf\u00fchrt.<\/li>\n<li>Legen Sie Ihr Budget fest und teilen Sie es dem Kreativen mit.<\/li>\n<li>Legen Sie Fristen f\u00fcr erste und letzte Entw\u00fcrfe fest.<\/li>\n<li>Achten Sie darauf, dass die festgelegten Fristen mit Ihren Redaktions- und Publikationsterminen \u00fcbereinstimmen und planen Sie gen\u00fcgend Zeit ein, falls \u00c4nderungen erforderlich sind.<\/li>\n<\/ul>\n<p>Dieses kostenlose Briefing-Formular bietet Ihnen eine solide Basis f\u00fcr die Entwicklung Ihres Agentur-Briefings.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt | english content<\/title>\n<meta name=\"description\" content=\"Bevor Sie einen englischen Texter engagieren, erstellen Sie ein Briefing \u00fcber das Format, die Zielgruppe und die Customer Journey.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt | english content\" \/>\n<meta property=\"og:description\" content=\"Bevor Sie einen englischen Texter engagieren, erstellen Sie ein Briefing \u00fcber das Format, die Zielgruppe und die Customer Journey.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft\" \/>\n<meta property=\"og:site_name\" content=\"english content\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-21T20:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T11:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/english-content.com\/wp-content\/uploads\/2021\/01\/storytelling-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MurielBurke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MurielBurke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft\"},\"author\":{\"name\":\"MurielBurke\",\"@id\":\"https:\\\/\\\/english-content.com\\\/de#\\\/schema\\\/person\\\/cc7d9a99e0fcc8f13f679728327f23f3\"},\"headline\":\"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt\",\"datePublished\":\"2022-04-21T20:15:00+00:00\",\"dateModified\":\"2022-07-04T11:08:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft\"},\"wordCount\":1011,\"image\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/english-content.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/storytelling-01.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft\",\"url\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft\",\"name\":\"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt | english content\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/english-content.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/storytelling-01.jpg\",\"datePublished\":\"2022-04-21T20:15:00+00:00\",\"dateModified\":\"2022-07-04T11:08:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de#\\\/schema\\\/person\\\/cc7d9a99e0fcc8f13f679728327f23f3\"},\"description\":\"Bevor Sie einen englischen Texter engagieren, erstellen Sie ein Briefing \u00fcber das Format, die Zielgruppe und die Customer Journey.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft#primaryimage\",\"url\":\"https:\\\/\\\/english-content.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/storytelling-01.jpg\",\"contentUrl\":\"https:\\\/\\\/english-content.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/storytelling-01.jpg\",\"width\":1440,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/english-content.com\\\/de\\\/wie-man-einen-texter-brieft#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/english-content.com\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/english-content.com\\\/de#website\",\"url\":\"https:\\\/\\\/english-content.com\\\/de\",\"name\":\"English-Content\",\"description\":\"Native English Copywriting for International Communications\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/english-content.com\\\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/english-content.com\\\/de#\\\/schema\\\/person\\\/cc7d9a99e0fcc8f13f679728327f23f3\",\"name\":\"MurielBurke\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0e2d99b610c7074b1f274d1ed4c62cd1fef4a27fae5afc346d7fd8327ad628b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0e2d99b610c7074b1f274d1ed4c62cd1fef4a27fae5afc346d7fd8327ad628b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0e2d99b610c7074b1f274d1ed4c62cd1fef4a27fae5afc346d7fd8327ad628b?s=96&d=mm&r=g\",\"caption\":\"MurielBurke\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt | english content","description":"Bevor Sie einen englischen Texter engagieren, erstellen Sie ein Briefing \u00fcber das Format, die Zielgruppe und die Customer Journey.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft","og_locale":"de_DE","og_type":"article","og_title":"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt | english content","og_description":"Bevor Sie einen englischen Texter engagieren, erstellen Sie ein Briefing \u00fcber das Format, die Zielgruppe und die Customer Journey.","og_url":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft","og_site_name":"english content","article_published_time":"2022-04-21T20:15:00+00:00","article_modified_time":"2022-07-04T11:08:06+00:00","og_image":[{"width":1440,"height":1440,"url":"https:\/\/english-content.com\/wp-content\/uploads\/2021\/01\/storytelling-01.jpg","type":"image\/jpeg"}],"author":"MurielBurke","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"MurielBurke","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft#article","isPartOf":{"@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft"},"author":{"name":"MurielBurke","@id":"https:\/\/english-content.com\/de#\/schema\/person\/cc7d9a99e0fcc8f13f679728327f23f3"},"headline":"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt","datePublished":"2022-04-21T20:15:00+00:00","dateModified":"2022-07-04T11:08:06+00:00","mainEntityOfPage":{"@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft"},"wordCount":1011,"image":{"@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft#primaryimage"},"thumbnailUrl":"https:\/\/english-content.com\/wp-content\/uploads\/2021\/01\/storytelling-01.jpg","articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft","url":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft","name":"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt | english content","isPartOf":{"@id":"https:\/\/english-content.com\/de#website"},"primaryImageOfPage":{"@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft#primaryimage"},"image":{"@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft#primaryimage"},"thumbnailUrl":"https:\/\/english-content.com\/wp-content\/uploads\/2021\/01\/storytelling-01.jpg","datePublished":"2022-04-21T20:15:00+00:00","dateModified":"2022-07-04T11:08:06+00:00","author":{"@id":"https:\/\/english-content.com\/de#\/schema\/person\/cc7d9a99e0fcc8f13f679728327f23f3"},"description":"Bevor Sie einen englischen Texter engagieren, erstellen Sie ein Briefing \u00fcber das Format, die Zielgruppe und die Customer Journey.","breadcrumb":{"@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft#primaryimage","url":"https:\/\/english-content.com\/wp-content\/uploads\/2021\/01\/storytelling-01.jpg","contentUrl":"https:\/\/english-content.com\/wp-content\/uploads\/2021\/01\/storytelling-01.jpg","width":1440,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/english-content.com\/de\/wie-man-einen-texter-brieft#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/english-content.com\/de"},{"@type":"ListItem","position":2,"name":"Wie man ein Briefing f\u00fcr einen Content-Autor oder -Strategen erstellt"}]},{"@type":"WebSite","@id":"https:\/\/english-content.com\/de#website","url":"https:\/\/english-content.com\/de","name":"English-Content","description":"Native English Copywriting for International Communications","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/english-content.com\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/english-content.com\/de#\/schema\/person\/cc7d9a99e0fcc8f13f679728327f23f3","name":"MurielBurke","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f0e2d99b610c7074b1f274d1ed4c62cd1fef4a27fae5afc346d7fd8327ad628b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0e2d99b610c7074b1f274d1ed4c62cd1fef4a27fae5afc346d7fd8327ad628b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0e2d99b610c7074b1f274d1ed4c62cd1fef4a27fae5afc346d7fd8327ad628b?s=96&d=mm&r=g","caption":"MurielBurke"}}]}},"_links":{"self":[{"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/posts\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/comments?post=600"}],"version-history":[{"count":5,"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/posts\/600\/revisions"}],"predecessor-version":[{"id":644,"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/posts\/600\/revisions\/644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/media\/237"}],"wp:attachment":[{"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/media?parent=600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/categories?post=600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english-content.com\/de\/wp-json\/wp\/v2\/tags?post=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}